{"id":4166,"date":"2019-05-24T11:22:05","date_gmt":"2019-05-24T11:22:05","guid":{"rendered":"\/es\/?p=4166"},"modified":"2020-05-08T15:48:02","modified_gmt":"2020-05-08T15:48:02","slug":"armerixia-aldizkariaren-3-alea","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/","title":{"rendered":"Armerixia: se ha publicado el tercer n\u00famero de la revista"},"content":{"rendered":"<p style=\"text-align: left;\">Ya est\u00e1 disponible<strong>\u00a0ARMERIXIA,<\/strong>\u00a0el tercer n\u00famero de la nueva revista de Armeria Eskola. En ella podr\u00e9is conocer los diferentes proyectos y actividades que se han desarrollado en la escuela durante el curso 2018\/19.<\/p>\n<div data-url=\"https:\/\/issuu.com\/armeriaeskola\/docs\/armerixian_3-digital\" style=\"width: 640px; height: 453px;\" class=\"issuuembed\"><\/div>\n<p><script type=\"text\/javascript\" src=\"\/\/e.issuu.com\/embed.js\" async=\"true\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 disponible\u00a0ARMERIXIA,\u00a0el tercer n\u00famero de la nueva revista de Armeria Eskola. En ella podr\u00e9is conocer los diferentes proyectos y actividades que se han desarrollado en la escuela durante el curso 2018\/19.<\/p>\n","protected":false},"author":6,"featured_media":4170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[215],"tags":[220,251],"class_list":["post-4166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-ae","tag-armeria-eskola","tag-revista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"Ya est\u00e1 disponible\u00a0ARMERIXIA,\u00a0el tercer n\u00famero de la nueva revista de Armeria Eskola. En ella podr\u00e9is conocer los diferentes proyectos y actividades que se han desarrollado en la escuela durante el curso 2018\/19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-24T11:22:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-08T15:48:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1331\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"Armerixia: se ha publicado el tercer n\u00famero de la revista\",\"datePublished\":\"2019-05-24T11:22:05+00:00\",\"dateModified\":\"2020-05-08T15:48:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/\"},\"wordCount\":53,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/potada-1.png\",\"keywords\":[\"Armeria Eskola\",\"revista\"],\"articleSection\":[\"Noticias-AE\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/\",\"name\":\"Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/potada-1.png\",\"datePublished\":\"2019-05-24T11:22:05+00:00\",\"dateModified\":\"2020-05-08T15:48:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/potada-1.png\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/potada-1.png\",\"width\":1331,\"height\":849},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/armerixia-aldizkariaren-3-alea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Armerixia: se ha publicado el tercer n\u00famero de la revista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/","og_locale":"es_ES","og_type":"article","og_title":"Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola","og_description":"Ya est\u00e1 disponible\u00a0ARMERIXIA,\u00a0el tercer n\u00famero de la nueva revista de Armeria Eskola. En ella podr\u00e9is conocer los diferentes proyectos y actividades que se han desarrollado en la escuela durante el curso 2018\/19.","og_url":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2019-05-24T11:22:05+00:00","article_modified_time":"2020-05-08T15:48:02+00:00","og_image":[{"width":1331,"height":849,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png","type":"image\/png"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"Armerixia: se ha publicado el tercer n\u00famero de la revista","datePublished":"2019-05-24T11:22:05+00:00","dateModified":"2020-05-08T15:48:02+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/"},"wordCount":53,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png","keywords":["Armeria Eskola","revista"],"articleSection":["Noticias-AE"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/","url":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/","name":"Armerixia: se ha publicado el tercer n\u00famero de la revista - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png","datePublished":"2019-05-24T11:22:05+00:00","dateModified":"2020-05-08T15:48:02+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/2019\/05\/potada-1.png","width":1331,"height":849},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/armerixia-aldizkariaren-3-alea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Armerixia: se ha publicado el tercer n\u00famero de la revista"}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/4166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=4166"}],"version-history":[{"count":0,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/4166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/4170"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=4166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=4166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=4166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}