{"id":24983,"date":"2025-05-08T09:10:23","date_gmt":"2025-05-08T07:10:23","guid":{"rendered":"https:\/\/armeriaeskola.eus\/?p=24983"},"modified":"2025-05-08T09:10:23","modified_gmt":"2025-05-08T07:10:23","slug":"la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/","title":{"rendered":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado"},"content":{"rendered":"<p>Entre enero y abril, convocados por los sindicatos STEILAS, LAB, ELA y CCOO, con una representaci\u00f3n del 90%, los profesores han secundado nueve jornadas de huelga. Las propuestas planteadas hasta el momento por el Departamento de Educaci\u00f3n, por su parte, no han dado respuesta adecuada a los contenidos promulgados. De hecho, en una ocasi\u00f3n han se\u00f1alado que <strong>faltan contenidos, concreciones y garant\u00edas.<\/strong><\/p>\n<p>As\u00ed, las huelgas y movilizaciones exitosas llevadas a cabo hasta el momento tendr\u00e1n continuidad con otras<strong> 5 huelgas los d\u00edas 12, 13, 14, 15 y 16 de mayo.<\/strong><\/p>\n<p>Hay que recordar que el acuerdo laboral del profesorado vigente es del 2010, por lo que el Gobierno Vasco lleva 15 a\u00f1os sin renovarlo. Cabe destacar tambi\u00e9n que las huelgas de mayo fueron anunciadas el 10 de abril y <strong>desde entonces los sindicatos no han recibido ninguna convocatoria para reunirse con el Departamento de Educaci\u00f3n.<\/strong><\/p>\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12\">La situaci\u00f3n actual del profesorado es cada vez m\u00e1s preocupante y necesitan nuevos recursos para mejorar el proceso de aprendizaje de nuestros alumnos;<br \/>\nmedidas concretas para aliviar las cargas de trabajo cada vez mayores. Necesitan tambi\u00e9n mejora de las condiciones de jubilaci\u00f3n y desarrollo del plan de rejuvenecimiento de las plantillas, con la excusa de la natalidad se est\u00e1n decidiendo unilateralmente fusiones y cierres de centros p\u00fablicos; Hay que garantizar el empleo p\u00fablico y estabilizar los puestos de trabajo.<\/div>\n<div class=\"col-md-12 col-xs-12\">Asimismo faltan, pol\u00edticas educativas que euskaldunicen el conjunto del sistema educativo p\u00fablico, vigilancia de la salud laboral, desarrollo de planes de igualdad y coeducaci\u00f3n de calidad. Por todo ello hay que establecer los recursos personales y las formaciones necesarias para el desarrollo de los mismos, eliminando los retrocesos impuestos en los \u00faltimos a\u00f1os.<br \/>\nLa comunidad educativa y muchos padres y madres miran con responsabilidad la situaci\u00f3n actual. La calidad de la educaci\u00f3n de alumnos\/as est\u00e1 en juego. Por ello, <strong>toda la comunidad educativa ha hecho una convocatoria para apoyar las huelgas y para sumarse a las reivindicaciones.<\/strong><\/div>\n<div class=\"col-md-12 col-xs-12\">As\u00ed, el s\u00e1bado <strong>10 de mayo<\/strong>, todos se reunir\u00e1n y convocar\u00e1n <strong>manifestaciones<\/strong> en las tres capitales vascas: En Donostia-San Sebasti\u00e1n, a las 17:00 horas, y en Bilbao y Vitoria-Gasteiz a las 18:00 horas.<br \/>\nPara reforzar la educaci\u00f3n p\u00fablica es imprescindible aumentar la inversi\u00f3n, mejorar las condiciones laborales y dotar de recursos la escuela p\u00fablica para mejorar la calidad educativa de nuestros hijos e hijas.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre enero y abril, convocados por los sindicatos STEILAS, LAB, ELA y CCOO, con una representaci\u00f3n del 90%, los profesores han secundado nueve jornadas de huelga. Las propuestas planteadas hasta el momento por el Departamento de Educaci\u00f3n, por su parte, &hellip; <\/p>\n","protected":false},"author":6,"featured_media":24981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-24983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"Entre enero y abril, convocados por los sindicatos STEILAS, LAB, ELA y CCOO, con una representaci\u00f3n del 90%, los profesores han secundado nueve jornadas de huelga. Las propuestas planteadas hasta el momento por el Departamento de Educaci\u00f3n, por su parte, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T07:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado\",\"datePublished\":\"2025-05-08T07:10:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/IMG_8854-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/\",\"name\":\"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/IMG_8854-scaled.jpg\",\"datePublished\":\"2025-05-08T07:10:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/IMG_8854-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/IMG_8854-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/","og_locale":"es_ES","og_type":"article","og_title":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola","og_description":"Entre enero y abril, convocados por los sindicatos STEILAS, LAB, ELA y CCOO, con una representaci\u00f3n del 90%, los profesores han secundado nueve jornadas de huelga. Las propuestas planteadas hasta el momento por el Departamento de Educaci\u00f3n, por su parte, &hellip;","og_url":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2025-05-08T07:10:23+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg","type":"image\/jpeg"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado","datePublished":"2025-05-08T07:10:23+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/"},"wordCount":418,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/","url":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/","name":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg","datePublished":"2025-05-08T07:10:23+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/IMG_8854-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/la-comunidad-educativa-publica-llama-a-secundar-la-convocatoria-de-huelga-del-profesorado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"La comunidad educativa p\u00fablica llama a secundar la convocatoria de huelga del profesorado"}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/24983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=24983"}],"version-history":[{"count":1,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/24983\/revisions"}],"predecessor-version":[{"id":24984,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/24983\/revisions\/24984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/24981"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=24983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=24983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=24983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}