{"id":22524,"date":"2023-12-01T17:23:30","date_gmt":"2023-12-01T16:23:30","guid":{"rendered":"https:\/\/armeriaeskola.eus\/?p=22524"},"modified":"2023-12-03T11:00:10","modified_gmt":"2023-12-03T10:00:10","slug":"alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/","title":{"rendered":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista"},"content":{"rendered":"<p>En el ciclo formativo superior de Telecomunicaciones y Sistemas Inform\u00e1ticos el alumnado se forma en redes inform\u00e1ticas, sistemas audiovisuales, radiocomunicaciones, mantenimiento de sistemas de telecomunicaciones e infraestructuras comunes de telecomunicaciones.<\/p>\n<p>En el primer trimestre de este a\u00f1o acad\u00e9mico, de octubre a diciembre, el alumnado de 2\u00ba curso ha trabajado en profundidad durante ocho semanas la parte t\u00e9cnica de los audiovisuales. Al final, han tenido que afrontar un gran reto: tuvieron que transmitir en directo la entrevista al trikitilari y artista Julen Alonso para Hamaika Telebista, que emite en toda Euskal Herria.<\/p>\n<p>A trav\u00e9s de competencias como la autonom\u00eda y el trabajo en equipo, base del modelo de aprendizaje ETHAZI (Ciclos de Alto Rendimiento), el alumnado, bajo la bajo la direcci\u00f3n de sus docentes, han llegado a conocer\u00a0 todos los detalles que incluye la realizaci\u00f3n de un programa, las configuraciones de la c\u00e1mara y las claves para asegurar las conexiones de audio y v\u00eddeo adecuadas.<\/p>\n<p>Adem\u00e1s de trabajar tanto las competencias t\u00e9cnicas como las transversales, contribuyeron al fomento del euskera y la cultura vasca.<\/p>\n<p>\u00a1Felicidades por el trabajo bien hecho y nuestro agradecimiento al trikitilari Julen Alonso, a la periodista Malen Altuna y a Hamaika Telebista por facilitar el aprendizaje de nuestro alumnado!<\/p>\n<p><iframe loading=\"lazy\" title=\"Zuzeneko emanaldia \/\/ Hamaika Telebista\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/jR_5v6XAyB8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el ciclo formativo superior de Telecomunicaciones y Sistemas Inform\u00e1ticos el alumnado se forma en redes inform\u00e1ticas, sistemas audiovisuales, radiocomunicaciones, mantenimiento de sistemas de telecomunicaciones e infraestructuras comunes de telecomunicaciones. En el primer trimestre de este a\u00f1o acad\u00e9mico, de octubre &hellip; <\/p>\n","protected":false},"author":6,"featured_media":22522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-22524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"En el ciclo formativo superior de Telecomunicaciones y Sistemas Inform\u00e1ticos el alumnado se forma en redes inform\u00e1ticas, sistemas audiovisuales, radiocomunicaciones, mantenimiento de sistemas de telecomunicaciones e infraestructuras comunes de telecomunicaciones. En el primer trimestre de este a\u00f1o acad\u00e9mico, de octubre &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T16:23:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-03T10:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2038\" \/>\n\t<meta property=\"og:image:height\" content=\"1188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista\",\"datePublished\":\"2023-12-01T16:23:30+00:00\",\"dateModified\":\"2023-12-03T10:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/TIS-eko-erronka-Kopia.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/\",\"name\":\"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/TIS-eko-erronka-Kopia.jpeg\",\"datePublished\":\"2023-12-01T16:23:30+00:00\",\"dateModified\":\"2023-12-03T10:00:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/TIS-eko-erronka-Kopia.jpeg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/TIS-eko-erronka-Kopia.jpeg\",\"width\":2038,\"height\":1188},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/","og_locale":"es_ES","og_type":"article","og_title":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola","og_description":"En el ciclo formativo superior de Telecomunicaciones y Sistemas Inform\u00e1ticos el alumnado se forma en redes inform\u00e1ticas, sistemas audiovisuales, radiocomunicaciones, mantenimiento de sistemas de telecomunicaciones e infraestructuras comunes de telecomunicaciones. En el primer trimestre de este a\u00f1o acad\u00e9mico, de octubre &hellip;","og_url":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2023-12-01T16:23:30+00:00","article_modified_time":"2023-12-03T10:00:10+00:00","og_image":[{"width":2038,"height":1188,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg","type":"image\/jpeg"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista","datePublished":"2023-12-01T16:23:30+00:00","dateModified":"2023-12-03T10:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/"},"wordCount":239,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/","url":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/","name":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg","datePublished":"2023-12-01T16:23:30+00:00","dateModified":"2023-12-03T10:00:10+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/TIS-eko-erronka-Kopia.jpeg","width":2038,"height":1188},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/alumnado-del-ciclo-de-telecomunicaciones-y-sistemas-informaticos-emitieron-una-entrevista-en-directo-para-hamaika-telebista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Alumnado del ciclo de Telecomunicaciones y Sistemas Inform\u00e1ticos emiti\u00f3 en directo para Hamaika Telebista"}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/22524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=22524"}],"version-history":[{"count":3,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/22524\/revisions"}],"predecessor-version":[{"id":22528,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/22524\/revisions\/22528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/22522"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=22524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=22524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=22524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}