{"id":17145,"date":"2021-05-06T16:43:01","date_gmt":"2021-05-06T14:43:01","guid":{"rendered":"https:\/\/armeriaeskola.eus\/?p=17145"},"modified":"2021-05-06T16:43:01","modified_gmt":"2021-05-06T14:43:01","slug":"el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/","title":{"rendered":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera."},"content":{"rendered":"<p>En rueda de prensa celebrada en el Ayuntamiento de Eibar, el alcalde de la ciudad, Jon Iraola, la Presidenta de la Comisi\u00f3n de Desarrollo Econ\u00f3mico, Empleo e Innovaci\u00f3n, Ana Telleria, el director de UNI Eibar, Oskar Gisasola, el director de estrategia de Armeria Eskola, Iker Espilla, y alumnos de ambos centros de han numerado las ventajas de realizar la Formaci\u00f3n Profesional en euskera, destacando las siguientes:<\/p>\n<ul>\n<li>Las empresas m\u00e1s avanzadas de la zona valoran el conocimiento del euskera en las nuevas contrataciones.<\/li>\n<li>El entorno laboral de muchas empresas es euskaldun y en los puestos de trabajo que tienen contacto con los clientes requieren una capacitaci\u00f3n en euskera, ya que cuando los clientes son atendidos en la lengua tienen una mayor satisfacci\u00f3n.<\/li>\n<li>En las contrataciones p\u00fablicas (Osakidetza, Educaci\u00f3n, Kabia, Ayuntamientos, Mancomunidades&#8230;) el conocimiento del euskera y la posesi\u00f3n de certificados B1 o B2 son requisitos imprescindibles.<\/li>\n<li>Quien hayo cursado los estudios de DBH y bachillerato euskera est\u00e1 totalmente capacitado para realizar la Formaci\u00f3n Profesional en el modelo D.<\/li>\n<li>Cursando sus estudios en euskera tendr\u00e1n una formaci\u00f3n m\u00e1s completa, ya que dominar\u00e1n ambas lenguas oficiales.<\/li>\n<li>Cursando un grado medio en euskera se obtiene el certificado B1, y cursando un grado superior el B2<\/li>\n<\/ul>\n<p>El alcalde de Eibar y la presidenta de la Comisi\u00f3n de Desarrollo Econ\u00f3mico, Empleo e Innovaci\u00f3n han se\u00f1alado que el Ayuntamiento de Eibar trabaja desde la d\u00e9cada de los 80 en la normalizaci\u00f3n del uso del euskera en el municipio y en la administraci\u00f3n. El ayuntamiento siempre ha tenido claro la importancia del sistema educativo en la normalizaci\u00f3n del euskera, y quiere seguir siendo un aliado como hasta lo ha sido hasta ahora.<\/p>\n<p>El hecho de que en el sistema educativo casi todos los ni\u00f1os eibarreses sean escolarizados en el modelo d garantiza que en pocos a\u00f1os casi todos los ciudadanos ser\u00e1n biling\u00fces, todos ser\u00e1n capaces al menos de entender el euskera, lo que permitir\u00e1 a quien quiera vivir en euskera utilizarlo en todos los \u00e1mbitos.<br \/>\nUna vez realizada la Educaci\u00f3n Obligatoria en el modelo D, lo m\u00e1s adecuado es que la Formaci\u00f3n Profesional tambi\u00e9n se realice en ese mismo modelo.<\/p>\n<p>La matriculaci\u00f3n en el modelo D dar\u00e1 un plus a la formaci\u00f3n del alumno de cara al mercado laboral. De hecho, tanto en el sector empresarial como en el de servicios cada vez se pide m\u00e1s el conocimiento del euskera.<\/p>\n<p>Hay que decir que el Gobierno Vasco tiene en vigor un plan de promoci\u00f3n del euskera en el \u00e1mbito socioecon\u00f3mico, uno de cuyos objetivos finales, que comparte el Ayuntamiento de Eibar, es el de aumentar el n\u00famero de alumnos que estudian en euskera en la Formaci\u00f3n Profesional. \u00a0En dicho plan se recoge el incremento del uso del euskera como lengua de servicio en las empresas de servicios de las comarcas, as\u00ed como un mayor uso del euskera como lengua de trabajo en las industrias de la comarca.<\/p>\n<p>Acto seguido, los directores de los centros de Formaci\u00f3n Profesional de UNI Eibar y Armeria Eskola han resaltado su apuesta por aumentar la presencia y el uso del euskera en sus centros y han repasado la evoluci\u00f3n de la matriculaci\u00f3n en los modelos D de euskera.<\/p>\n<p>As\u00ed, en la \u00faltima d\u00e9cada el incremento de la matriculaci\u00f3n en el modelo D ha side del 60% cada vez ofrecen m\u00e1s ciclos formativos en los modelos D y B. Por ejemplo, el pr\u00f3ximo curso Armeria Eskola ofertar\u00e1 tres ciclos en el modelo B que hasta ahora se ofertaban en el modelo A. Dicho cambio se materializar\u00e1 el ciclo de grado medio de Mecanizado y en los ciclos de grado superior de Sistemas de Telecomunicaci\u00f3n e Inform\u00e1tica y Mantenimiento electr\u00f3nico.<\/p>\n<p>Los directores de ambos centros creen que, si bien el aumento ha sido sostenido y gradual, hay que seguir trabajando para conseguir el objetivo marcado para el a\u00f1o 2024 de que el 70-75% de los alumnos se matriculen en los modelos B o D<\/p>\n<p>Por \u00faltimo, los alumnos de ambos centros han relatado porqu\u00e9 optaron ellos por estudiar en euskera y\u00a0 han recomendado a todos los que est\u00e9n pensando hacer un ciclo formativo de Formaci\u00f3n Profesional que se matriculen en el modelo D.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En rueda de prensa celebrada en el Ayuntamiento de Eibar, el alcalde de la ciudad, Jon Iraola, la Presidenta de la Comisi\u00f3n de Desarrollo Econ\u00f3mico, Empleo e Innovaci\u00f3n, Ana Telleria, el director de UNI Eibar, Oskar Gisasola, el director de &hellip; <\/p>\n","protected":false},"author":6,"featured_media":17137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-17145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"En rueda de prensa celebrada en el Ayuntamiento de Eibar, el alcalde de la ciudad, Jon Iraola, la Presidenta de la Comisi\u00f3n de Desarrollo Econ\u00f3mico, Empleo e Innovaci\u00f3n, Ana Telleria, el director de UNI Eibar, Oskar Gisasola, el director de &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-06T14:43:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera.\",\"datePublished\":\"2021-05-06T14:43:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/\"},\"wordCount\":762,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/\",\"name\":\"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg\",\"datePublished\":\"2021-05-06T14:43:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/","og_locale":"es_ES","og_type":"article","og_title":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola","og_description":"En rueda de prensa celebrada en el Ayuntamiento de Eibar, el alcalde de la ciudad, Jon Iraola, la Presidenta de la Comisi\u00f3n de Desarrollo Econ\u00f3mico, Empleo e Innovaci\u00f3n, Ana Telleria, el director de UNI Eibar, Oskar Gisasola, el director de &hellip;","og_url":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2021-05-06T14:43:01+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg","type":"image\/jpeg"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera.","datePublished":"2021-05-06T14:43:01+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/"},"wordCount":762,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/","url":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/","name":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera. - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg","datePublished":"2021-05-06T14:43:01+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/WhatsApp-Image-2021-05-06-at-11.32.26.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/el-ayuntamiento-de-eibar-y-los-centros-de-fp-uni-eibar-y-armeria-eskola-subrayan-las-ventajas-de-matricularse-en-el-modelo-d-en-euskera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"El ayuntamiento de Eibar y los centros de FP UNI EIbar Y Armeria Eskola subrayan las ventajas de matricularse en el modelo D en euskera."}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/17145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=17145"}],"version-history":[{"count":1,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/17145\/revisions"}],"predecessor-version":[{"id":17146,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/17145\/revisions\/17146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/17137"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=17145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=17145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=17145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}