{"id":16849,"date":"2021-04-13T17:10:57","date_gmt":"2021-04-13T15:10:57","guid":{"rendered":"https:\/\/armeriaeskola.eus\/?p=16849"},"modified":"2021-04-15T11:19:04","modified_gmt":"2021-04-15T09:19:04","slug":"competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/","title":{"rendered":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas."},"content":{"rendered":"<p>Los alumnos del ciclo<a href=\"https:\/\/armeriaeskola.eus\/es\/estudios\/grado-medio\/instalaciones-electricas-y-automaticas\/\"> Instalaciones El\u00e9ctricas y Autom\u00e1ticas<\/a>, divididos en siete grupos de tres, participar\u00e1n en la primera edici\u00f3n del concurso Armeria Eskola Skills.<br \/>\nLa competici\u00f3n, cuya duraci\u00f3n ser\u00e1 de una semana, tendr\u00e1 la misma estructura que la prueba Eusko Skills celebrada en 2018. Los alumnos deber\u00e1n superar dos grandes retos: el primero, montar un automatismo y el segundo, realizar la instalaci\u00f3n el\u00e9ctrica de una vivienda. Este es el calendario:<\/p>\n<ul>\n<li>Lunes: entrenamiento previo al automatismo el\u00e9ctrico<\/li>\n<li>Martes: primer reto de la competici\u00f3n: montaje de un automatismo el\u00e9ctrico. Siguiendo los planos y esquemas el\u00e9ctricos proporcionados por el profesorado, los siete equipos deber\u00e1n mecanizar, montar y conectar un automatismo el\u00e9ctrico<\/li>\n<li>Mi\u00e9rcoles: verificaci\u00f3n de los automatismos realizados y entrenamiento previo para el segundo reto.<\/li>\n<li>Jueves: segundo reto de la competici\u00f3n: montaje de una instalaci\u00f3n el\u00e9ctrica de una vivienda. Siguiendo los esquemas y materiales el\u00e9ctricos facilitados por el profesorado, el alumnado deber\u00e1 realizar la instalaci\u00f3n el\u00e9ctrica de una vivienda.<\/li>\n<li>Viernes: verificaciones finales de los retos, entrega de premios y reflexiones finales.<\/li>\n<\/ul>\n<p>El concurso comenz\u00f3 el pasado lunes y seg\u00fan el profesor Joseba Altuna, los alumnos est\u00e1n muy motivados y con ganas de poner en pr\u00e1ctica todo lo aprendido hasta la fecha.<\/p>\n<p><iframe loading=\"lazy\" title=\"Armeria Eskola Skills 20\/21\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/VslPJyr65ys?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos del ciclo Instalaciones El\u00e9ctricas y Autom\u00e1ticas, divididos en siete grupos de tres, participar\u00e1n en la primera edici\u00f3n del concurso Armeria Eskola Skills. La competici\u00f3n, cuya duraci\u00f3n ser\u00e1 de una semana, tendr\u00e1 la misma estructura que la prueba Eusko &hellip; <\/p>\n","protected":false},"author":6,"featured_media":16846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-16849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"Los alumnos del ciclo Instalaciones El\u00e9ctricas y Autom\u00e1ticas, divididos en siete grupos de tres, participar\u00e1n en la primera edici\u00f3n del concurso Armeria Eskola Skills. La competici\u00f3n, cuya duraci\u00f3n ser\u00e1 de una semana, tendr\u00e1 la misma estructura que la prueba Eusko &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T15:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T09:19:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas.\",\"datePublished\":\"2021-04-13T15:10:57+00:00\",\"dateModified\":\"2021-04-15T09:19:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Copia-de-Clil-2.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/\",\"name\":\"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Copia-de-Clil-2.jpg\",\"datePublished\":\"2021-04-13T15:10:57+00:00\",\"dateModified\":\"2021-04-15T09:19:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Copia-de-Clil-2.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Copia-de-Clil-2.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/","og_locale":"es_ES","og_type":"article","og_title":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola","og_description":"Los alumnos del ciclo Instalaciones El\u00e9ctricas y Autom\u00e1ticas, divididos en siete grupos de tres, participar\u00e1n en la primera edici\u00f3n del concurso Armeria Eskola Skills. La competici\u00f3n, cuya duraci\u00f3n ser\u00e1 de una semana, tendr\u00e1 la misma estructura que la prueba Eusko &hellip;","og_url":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2021-04-13T15:10:57+00:00","article_modified_time":"2021-04-15T09:19:04+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg","type":"image\/jpeg"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas.","datePublished":"2021-04-13T15:10:57+00:00","dateModified":"2021-04-15T09:19:04+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/"},"wordCount":244,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/","url":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/","name":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas. - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg","datePublished":"2021-04-13T15:10:57+00:00","dateModified":"2021-04-15T09:19:04+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Copia-de-Clil-2.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/competicion-de-armeria-eskola-skills-en-el-ciclo-formativo-instalaciones-electricas-y-automaticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Competici\u00f3n de Armeria Eskola Skills, en el ciclo formativo Instalaciones El\u00e9ctricas y Autom\u00e1ticas."}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=16849"}],"version-history":[{"count":3,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16849\/revisions"}],"predecessor-version":[{"id":16864,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16849\/revisions\/16864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/16846"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=16849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=16849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=16849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}