{"id":16079,"date":"2021-02-05T13:58:44","date_gmt":"2021-02-05T12:58:44","guid":{"rendered":"https:\/\/armeriaeskola.eus\/?p=16079"},"modified":"2021-02-05T14:05:11","modified_gmt":"2021-02-05T13:05:11","slug":"16079","status":"publish","type":"post","link":"https:\/\/armeriaeskola.eus\/es\/16079\/","title":{"rendered":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola"},"content":{"rendered":"<p>Este a\u00f1o la Feria Ikasenpresa se ha desarrollado de forma virtual y los grupos han realizado sendos v\u00eddeos presentando sus proyectos empresariales.<\/p>\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12\">Aqu\u00ed pod\u00e9is ver los v\u00eddeos<\/div>\n<div><\/div>\n<div>\n<p><iframe loading=\"lazy\" title=\"Ikasenpresa Azora Birtuala 2021\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PLFRzZTkCfQU6o2ksNorzAB40QvKvas6t0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o la Feria Ikasenpresa se ha desarrollado de forma virtual y los grupos han realizado sendos v\u00eddeos presentando sus proyectos empresariales. Aqu\u00ed pod\u00e9is ver los v\u00eddeos &nbsp;<\/p>\n","protected":false},"author":6,"featured_media":16081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-16079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/armeriaeskola.eus\/es\/16079\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o la Feria Ikasenpresa se ha desarrollado de forma virtual y los grupos han realizado sendos v\u00eddeos presentando sus proyectos empresariales. Aqu\u00ed pod\u00e9is ver los v\u00eddeos &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/armeriaeskola.eus\/es\/16079\/\" \/>\n<meta property=\"og:site_name\" content=\"Armeria Eskola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/armeriaeskola\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-05T12:58:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-05T13:05:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administratzailea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:site\" content=\"@ArmeriaEskola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administratzailea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/\"},\"author\":{\"name\":\"Administratzailea\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\"},\"headline\":\"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola\",\"datePublished\":\"2021-02-05T12:58:44+00:00\",\"dateModified\":\"2021-02-05T13:05:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Ikasenpresa-Azoka.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/\",\"name\":\"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Ikasenpresa-Azoka.jpg\",\"datePublished\":\"2021-02-05T12:58:44+00:00\",\"dateModified\":\"2021-02-05T13:05:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#primaryimage\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Ikasenpresa-Azoka.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/Ikasenpresa-Azoka.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/16079\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/armeriaeskola.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#website\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"name\":\"Armeria Eskola\",\"description\":\"Centro Integral P\u00fablico de Formaci\u00f3n Profesional\",\"publisher\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/armeriaeskola.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#organization\",\"name\":\"Armeria Eskola\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"contentUrl\":\"https:\\\/\\\/armeriaeskola.eus\\\/wp-content\\\/uploads\\\/armeria-eskola-youtube1.jpg\",\"width\":1000,\"height\":501,\"caption\":\"Armeria Eskola\"},\"image\":{\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/armeriaeskola\",\"https:\\\/\\\/x.com\\\/ArmeriaEskola\",\"https:\\\/\\\/www.instagram.com\\\/armeriaeskola\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/asociaciondearmeriaeskola\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/100armeriaeskola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/armeriaeskola.eus\\\/#\\\/schema\\\/person\\\/556cc6ece953729a0ba6f78b66e54fc9\",\"name\":\"Administratzailea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g\",\"caption\":\"Administratzailea\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/armeriaeskola.eus\/es\/16079\/","og_locale":"es_ES","og_type":"article","og_title":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola","og_description":"Este a\u00f1o la Feria Ikasenpresa se ha desarrollado de forma virtual y los grupos han realizado sendos v\u00eddeos presentando sus proyectos empresariales. Aqu\u00ed pod\u00e9is ver los v\u00eddeos &nbsp;","og_url":"https:\/\/armeriaeskola.eus\/es\/16079\/","og_site_name":"Armeria Eskola","article_publisher":"https:\/\/www.facebook.com\/armeriaeskola","article_published_time":"2021-02-05T12:58:44+00:00","article_modified_time":"2021-02-05T13:05:11+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg","type":"image\/jpeg"}],"author":"Administratzailea","twitter_card":"summary_large_image","twitter_creator":"@ArmeriaEskola","twitter_site":"@ArmeriaEskola","twitter_misc":{"Escrito por":"Administratzailea","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#article","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/"},"author":{"name":"Administratzailea","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9"},"headline":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola","datePublished":"2021-02-05T12:58:44+00:00","dateModified":"2021-02-05T13:05:11+00:00","mainEntityOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/"},"wordCount":58,"publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/armeriaeskola.eus\/es\/16079\/","url":"https:\/\/armeriaeskola.eus\/es\/16079\/","name":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola - Armeria Eskola","isPartOf":{"@id":"https:\/\/armeriaeskola.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#primaryimage"},"image":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#primaryimage"},"thumbnailUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg","datePublished":"2021-02-05T12:58:44+00:00","dateModified":"2021-02-05T13:05:11+00:00","breadcrumb":{"@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/armeriaeskola.eus\/es\/16079\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#primaryimage","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/Ikasenpresa-Azoka.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/armeriaeskola.eus\/es\/16079\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/armeriaeskola.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Feria Ikasenpresa 2021. Disponibles los videos de los proyectos empresariales presentados por el alumnado de Armeria Eskola"}]},{"@type":"WebSite","@id":"https:\/\/armeriaeskola.eus\/#website","url":"https:\/\/armeriaeskola.eus\/","name":"Armeria Eskola","description":"Centro Integral P\u00fablico de Formaci\u00f3n Profesional","publisher":{"@id":"https:\/\/armeriaeskola.eus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/armeriaeskola.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/armeriaeskola.eus\/#organization","name":"Armeria Eskola","url":"https:\/\/armeriaeskola.eus\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/","url":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","contentUrl":"https:\/\/armeriaeskola.eus\/wp-content\/uploads\/armeria-eskola-youtube1.jpg","width":1000,"height":501,"caption":"Armeria Eskola"},"image":{"@id":"https:\/\/armeriaeskola.eus\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/armeriaeskola","https:\/\/x.com\/ArmeriaEskola","https:\/\/www.instagram.com\/armeriaeskola\/","https:\/\/www.linkedin.com\/company\/asociaciondearmeriaeskola\/","https:\/\/www.youtube.com\/user\/100armeriaeskola"]},{"@type":"Person","@id":"https:\/\/armeriaeskola.eus\/#\/schema\/person\/556cc6ece953729a0ba6f78b66e54fc9","name":"Administratzailea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b2e098c27974ed137406b913c3d1ad97e377132fd5a6545df4ff35523a1f3c9?s=96&d=mm&r=g","caption":"Administratzailea"}}]}},"_links":{"self":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/comments?post=16079"}],"version-history":[{"count":6,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16079\/revisions"}],"predecessor-version":[{"id":16088,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/posts\/16079\/revisions\/16088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media\/16081"}],"wp:attachment":[{"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/media?parent=16079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/categories?post=16079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeriaeskola.eus\/es\/wp-json\/wp\/v2\/tags?post=16079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}